{"id":10266,"date":"2025-04-23T21:55:09","date_gmt":"2025-04-23T19:55:09","guid":{"rendered":"https:\/\/www.mtv-in.de\/schach\/?p=10266"},"modified":"2025-04-23T21:58:55","modified_gmt":"2025-04-23T19:58:55","slug":"mission-accomplished-saisonziele-erreicht","status":"publish","type":"post","link":"https:\/\/www.mtv-in.de\/schach\/2025\/04\/mission-accomplished-saisonziele-erreicht\/","title":{"rendered":"Mission accomplished &#8211; Saisonziele erreicht"},"content":{"rendered":"\n<p>In der Saison 2023\/24 sind wir bekanntlich mit mehreren Mannschaften in h\u00f6here Ligen aufgestiegen. Unsere erste Mannschaft schaffte den Aufstieg von der Bezirksliga Oberbayern in die Regionalliga S\u00fcdost. Die zweite Mannschaft schaffte den Sprung von der A-Klasse in die erste Kreisliga. Die erste U16-Jugendmannschaft stieg von der Kreisliga in die Bezirksliga Oberbayern auf.<\/p>\n\n\n\n<p><a href=\"http:\/\/www.mtv-in.de\/schach\/2024\/04\/mtv-schach-doppelter-aufstieg\/\">http:\/\/www.mtv-in.de\/schach\/2024\/04\/mtv-schach-doppelter-aufstieg\/<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/www.mtv-in.de\/schach\/2024\/10\/gelungener-saisonstart-2024-25\/\">https:\/\/www.mtv-in.de\/schach\/2024\/10\/gelungener-saisonstart-2024-25\/<\/a><\/p>\n\n\n\n<p>In der Saison 2024\/25 galt es also, sich in den h\u00f6heren Ligen zu behaupten, wohl wissend, dass es entsprechend schwer werden w\u00fcrde. Und wir haben es geschafft. Beide Mannschaften im Erwachsenenbereich konnten ihre Ligen halten. In der Regionalliga S\u00fcd-Ost war es mega spannend. Die Mannschaft mit den Spielern Markus Lechermann, Ralf Glawe, Patrick Eichschmied, Michael Holgert, Michael Vollnhals, Asim Muharemagic, Josef Freunddorfer und Kai Hausmann war vor der letzten Runde noch mit 5 anderen Mannschaften potenziell abstiegsgef\u00e4hrdet. Alle Mannschaften hatten nur 8 : 8 bzw. 7 : 9 Punkte (Pl\u00e4tze 4 bis 8) erreicht. In der vorletzten Runde konnten wir den Sack nicht zu machen. Der SK Neuburg stand bereits als Absteiger fest. Allerdings erreichten wir gegen Neuburg nur ein 4 : 4, so dass wir am letzten Spieltag beim Ausw\u00e4rtsspiel gegen den SK Bruckm\u00fchl entsprechend unter Druck standen. Aufgrund einiger Ausf\u00e4lle musste die erste Mannschaft am letzten Spieltag auch noch mit 2 Ersatzspielern antreten. Aber die Mission gelang und wir gewannen in Bruckm\u00fchl mit 5 : 3. Dies reichte f\u00fcr einen hervorragenden 5. Platz in der Regionalliga S\u00fcdost.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ligamanager.schachbund-bayern.de\/bsb\/ergebnisse\/spielplan.htm?ligaId=2341\">https:\/\/www.ligamanager.schachbund-bayern.de\/bsb\/ergebnisse\/spielplan.htm?ligaId=2341<\/a><\/p>\n\n\n\n<p>Die zweite Mannschaft um Leo, Eric und Daniel Navarro, Andreas Menrad, Armin G\u00fcrtler, Igor Beller, Sarah Hausmann und Peter Euringer lies \u00fcberhaupt nichts anbrennen und spielte die gesamte Saison in der Kreisliga vorne mit. Gleich in der ersten Runde gab es ein Achtungserfolg mit einem 4 : 4 gegen den SC Beilngries, dem Gewinner aus der Saison 2023\/24. Den sp\u00e4teren Sieger der Kreisliga (TSV Mainburg) haben wir in Runde 7 ebenfalls mit 5 : 3 geschlagen. Diese Mannschaft erk\u00e4mpfte 6 Siege, 1 Unentschieden und kassierte nur 2 Niederlagen. Die Belohnung am Saisonende ist Platz 4. Dabei haben wir genauso viele Mannschaftspunkte (13 : 5), wie der SC Beilngries auf Platz 2. Alles Ergebnisse sind hier zu finden:<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ligamanager.schachbund-bayern.de\/infs\/ergebnisse\/spielplan.htm?ligaId=2400\">https:\/\/www.ligamanager.schachbund-bayern.de\/infs\/ergebnisse\/spielplan.htm?ligaId=2400<\/a><\/p>\n\n\n\n<p>In der zweiten Mannschaften bekamen neben Leo und Eric auch unsere beiden Jugenspieler Konstantin Pappas und Pablo Graf de Miguel ein paar Eins\u00e4tze. Und Konstantin spielte insgesamt eine tolle Saison steuerte 3 Punkte aus 4 Runden zum Mannschaftserfolg bei. Beste Spieler waren Sarah Hausmann mit 4 Punkten aus 4 Runden,  Eric Navarro Jahnke mit 5,5 aus 8 und Tung Doan mit 4 aus 6.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>In der Saison 2023\/24 sind wir bekanntlich mit mehreren Mannschaften in h\u00f6here Ligen aufgestiegen. Unsere erste Mannschaft schaffte den Aufstieg von der Bezirksliga Oberbayern in die Regionalliga S\u00fcdost. Die zweite Mannschaft schaffte den Sprung von der A-Klasse in die erste Kreisliga. Die erste U16-Jugendmannschaft stieg von der Kreisliga in die Bezirksliga Oberbayern auf. http:\/\/www.mtv-in.de\/schach\/2024\/04\/mtv-schach-doppelter-aufstieg\/ https:\/\/www.mtv-in.de\/schach\/2024\/10\/gelungener-saisonstart-2024-25\/ [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":10261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-10266","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein"],"_links":{"self":[{"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/posts\/10266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/comments?post=10266"}],"version-history":[{"count":2,"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/posts\/10266\/revisions"}],"predecessor-version":[{"id":10269,"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/posts\/10266\/revisions\/10269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/media\/10261"}],"wp:attachment":[{"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/media?parent=10266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/categories?post=10266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mtv-in.de\/schach\/wp-json\/wp\/v2\/tags?post=10266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}