{"id":1325,"date":"2021-11-05T16:02:23","date_gmt":"2021-11-05T15:02:23","guid":{"rendered":"http:\/\/www.mtv-in.de\/tischtennis\/?p=1325"},"modified":"2021-11-05T16:02:23","modified_gmt":"2021-11-05T15:02:23","slug":"florian-teuber-schafft-quali-zur-bayerischen-meisterschaft","status":"publish","type":"post","link":"https:\/\/www.mtv-in.de\/tischtennis\/2021\/11\/florian-teuber-schafft-quali-zur-bayerischen-meisterschaft\/","title":{"rendered":"Florian Teuber schafft Quali zur Bayerischen Meisterschaft"},"content":{"rendered":"<p>Die Herren-A-Klasse war bei den Bezirksmeisterschaften fest in der Hand unserer Aktiven. Drei unter den ersten Vier, davon zwei im rein lilawei\u00dfen Endspiel. Das wurde nach einem wahren Krimi in sieben umk\u00e4mpften S\u00e4tzen zugunsten von Florian Teuber entschieden. Christoph Mader musste sich mit Rang zwei zufrieden geben, Frederik Erpenstein wurde Vierter.<\/p>\n<p>Damit gelang Florian Teuber zum wiederholten Mal die Qualifikation f\u00fcr die Bayerische Meisterschaft. An der Seite von Frederik Erpenstein sicherten sich beide auch den Titel im Doppel.<\/p>\n<p>Hervorzuheben ist zudem der 3. Platz von Dennis Oberholzner im Einzel der Herren-C-Klasse. Ebenfalls Dritte wurden Christopher und Andreas Heim im Doppel der E-Klasse. Andreas sicherte sich zus\u00e4tzlich Rang 4 im Einzel.<\/p>\n<p>Mit Dominik Nehir (Herren A) und Rupert Hintersteiner (Herren D) waren weitere MTVler am Start, so dass auch die gesamte Beteiligung unserer Aktiven nicht zu w\u00fcnschen \u00fcbrig lie\u00df.<\/p>\n<p>Bild v.l.: Christoph Mader (2.), Florian Teuber (1.), Frederik Erpenstein (4.), Johannes Faltermeier (3., DJK Altdorf)<\/p>\n<h3>Related Images:<\/h3>","protected":false},"excerpt":{"rendered":"<p>Die Herren-A-Klasse war bei den Bezirksmeisterschaften fest in der Hand unserer Aktiven. Drei unter den ersten Vier, davon zwei im rein lilawei\u00dfen Endspiel. Das wurde nach einem wahren Krimi in sieben umk\u00e4mpften S\u00e4tzen zugunsten von Florian Teuber entschieden. Christoph Mader musste sich mit Rang zwei zufrieden geben, Frederik Erpenstein wurde Vierter. Damit gelang Florian Teuber [&hellip;]<\/p>\n","protected":false},"author":150,"featured_media":1326,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1325","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/posts\/1325","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/users\/150"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/comments?post=1325"}],"version-history":[{"count":3,"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/posts\/1325\/revisions"}],"predecessor-version":[{"id":1329,"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/posts\/1325\/revisions\/1329"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/media\/1326"}],"wp:attachment":[{"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/media?parent=1325"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/categories?post=1325"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mtv-in.de\/tischtennis\/wp-json\/wp\/v2\/tags?post=1325"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}